{"id":3038,"date":"2025-11-04T18:07:35","date_gmt":"2025-11-04T07:07:35","guid":{"rendered":"https:\/\/www.amillex.com\/?p=3038"},"modified":"2025-12-23T19:33:36","modified_gmt":"2025-12-23T08:33:36","slug":"amillex-daily-market-review-tech-stocks-buoy-nasdaq-as-crypto-crashes-bitcoin-falls-over-4-below-106000-amazon-and-openai-sign-38-billion-ai-partnership","status":"publish","type":"post","link":"https:\/\/www.amillex.com\/de\/2025\/11\/04\/amillex-daily-market-review-tech-stocks-buoy-nasdaq-as-crypto-crashes-bitcoin-falls-over-4-below-106000-amazon-and-openai-sign-38-billion-ai-partnership\/","title":{"rendered":"Amillex Tagesmarkt\u00fcberblick: Tech-Aktien st\u00fctzen den Nasdaq nach Krypto-Crash \u2013 Bitcoin f\u00e4llt um \u00fcber 413 Billionen US-Dollar unter 106.000 US-Dollar; Amazon und OpenAI unterzeichnen KI-Partnerschaft im Wert von 38 Milliarden US-Dollar"},"content":{"rendered":"<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<h2 class=\"wp-block-heading\">4. November 2025 \u2013 Die US-Aktienm\u00e4rkte zeigten sich am Montag uneinheitlich. Der Nasdaq legte dank starker Kursgewinne von Amazon und Nvidia zu, w\u00e4hrend der S&amp;P 500 und der Dow Jones im Tagesverlauf nachgaben. Kryptow\u00e4hrungen brachen stark ein: Bitcoin fiel um \u00fcber 41,3 Billionen US-Dollar unter 106.000 US-Dollar, Ethereum verlor mehr als 81,3 Billionen US-Dollar. Der Goldpreis erholte sich nach einem zwischenzeitlichen R\u00fcckgang und notierte wieder \u00fcber 4.000 US-Dollar. Die \u00d6lpreise fanden Unterst\u00fctzung, nachdem die OPEC+ die Produktionssteigerungen ausgesetzt hatte. Die wichtigsten Marktthemen drehten sich um den anhaltenden Wettlauf zwischen dem Ausbau der KI-Infrastruktur und der politischen Unsicherheit.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">US-Aktien: Technologiewerte f\u00fchren die Gewinne an, nachdem AWS und OpenAI einen $38B-Compute-Deal unterzeichnen.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Der Nasdaq stieg zu Beginn der Sitzung um 1%, w\u00e4hrend der S&amp;P 500 um 0,2% nachgab und der Dow Jones um 0,3% fiel.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Spitzenreiter: Halbleiter (Micron +4%, Nvidia +2%), E-Commerce (Amazon +4,6%).<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Highlights:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Amazons AWS hat mit OpenAI einen Rechenleistungsvertrag im Wert von 1,4 Billionen US-Dollar abgeschlossen. OpenAI wird Hunderttausende von Nvidia-GPUs nutzen, um seine KI-Infrastrukturinitiative im Wert von 1,4 Billionen US-Dollar zu unterst\u00fctzen.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Microsoft k\u00fcndigte eine Investition von 1,4 Billionen PKR (7,9 Milliarden PKR) zum Ausbau der KI-Cloud-Infrastruktur in den VAE an, und IREN erhielt einen Cloud-Auftrag im Wert von 1,4 Billionen PKR (9,7 Milliarden PKR).<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Kernlogik: Explosive Investitionen in KI (Google emittierte Anleihen im Wert von 3 Milliarden Euro) glichen makro\u00f6konomische Bedenken aus, doch der Stillstand der US-Regierung (Tag 34) bremste weiterhin die allgemeine Marktbreite.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Kryptow\u00e4hrung: Bitcoin erreicht 2-Wochen-Tief inmitten regulatorischer und technischer Schwierigkeiten<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Bitcoin fiel um \u00fcber 41.030 auf 1.040.105.600, den niedrigsten Stand seit dem 17. Oktober.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Ethereum st\u00fcrzte um 81.030 Tsd. auf 1.040 Tsd. 3.590 Tsd. ab, w\u00e4hrend Solana und BNB beide um \u00fcber 51.030 Tsd. fielen.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Fahrer:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Technischer Fehler: Bitcoin durchbrach die wichtige Unterst\u00fctzung bei $108.000, was zu Liquidationen von gehebelten Long-Positionen f\u00fchrte.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Regulatorischer Gegenwind: Die US-B\u00f6rsenaufsicht SEC hat die Kontrollen von Stablecoins versch\u00e4rft, w\u00e4hrend die chinesische Zentralbank ihr Vorgehen gegen spekulativen Kryptohandel bekr\u00e4ftigt hat.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Die Kurse von Kryptow\u00e4hrungen brachen ein: Coinbase \u20134%, BitMine \u20138%, MicroStrategy \u20133%.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Rohstoffe: Gold erholt sich V-f\u00f6rmig; Aluminium erreicht Zweijahreshoch<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Der Goldpreis erholte sich von einem Tagestief von $3.960 und schloss mit einem Plus von 0,36% bei $4.017.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Politikwechsel: China hat seine Goldsteuerbefreiung abgeschafft; BullionVault sagte, dies k\u00f6nne die Nachfrage auf dem gr\u00f6\u00dften Konsummarkt der Welt d\u00e4mpfen.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Industriemetalle:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Der Aluminiumpreis an der LME stieg um 0,91 TP3T auf 1 TP4T2.909\/Tonne, den h\u00f6chsten Stand seit Mai 2022, und lag damit \u00fcber 71 TP3T im Oktober.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Der Kupferpreis an der LME stieg um 0,21 TP3T auf 10.903 TP4T\/Tonne und n\u00e4herte sich damit Rekordhochs.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">\u00d6l: Der Preis f\u00fcr WTI-Roh\u00f6l fiel um 0,51 TP3T unter 1 TP4T61, da die OPEC+ die Produktionssteigerungen aussetzte, die Nachfragesorgen jedoch anhielten.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Devisen &amp; Anleihen: Dollar stabil, SOFR-Zinssatz verzeichnet st\u00e4rksten Anstieg seit 2 Jahren<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Devisen: Der US-Dollar-Index blieb bei 98,60, der Yen geriet unter Druck und notierte bei etwa 153.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Geldm\u00e4rkte: Der Secured Overnight Financing Rate (SOFR) schnellte um 18 Basispunkte auf 4,22% in die H\u00f6he \u2013 der gr\u00f6\u00dfte Tagesanstieg seit 2023 \u2013 und signalisiert damit Liquidit\u00e4tsengp\u00e4sse zum Monatsende.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Europa: Der deutsche DAX stieg um 0,81 TP3T, w\u00e4hrend der britische FTSE 100 um 0,041 TP3T nachgab.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Heutiger Schwerpunkt:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Zinsentscheidung der RBA<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Einkaufsmanagerindizes und Besch\u00e4ftigungsdaten aus der Eurozone und den USA: Schwache Werte k\u00f6nnten die Erwartungen einer Lockerung der Konjunktur verst\u00e4rken.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Regierungsstillstand in den USA: Sollte dieser nicht beigelegt werden, k\u00f6nnte sich die Ver\u00f6ffentlichung der US-Arbeitsmarktdaten f\u00fcr Oktober (Ver\u00f6ffentlichung am 7. November) verz\u00f6gern.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Einnahmen:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">AMD und Qualcomm (nach B\u00f6rsenschluss): Bestellungen von KI-Chips best\u00e4tigen die Aussichten f\u00fcr die Partnerschaft mit OpenAI.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Palantir: Ein Umsatzwachstum im US-Gesch\u00e4ft von \u00fcber 501 Tsd. Billionen k\u00f6nnte die Dynamik von KI-Datenaktien befl\u00fcgeln.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Sitzung der Bank of England: Der Markt erwartet keine \u00c4nderung, aber eine breitere Stimmenaufteilung k\u00f6nnte die Volatilit\u00e4t des Pfund Sterling erh\u00f6hen.<\/h2>\n<\/blockquote>","protected":false},"excerpt":{"rendered":"<p>November 4, 2025 \u2014 U.S. equities were mixed on Monday, with the Nasdaq rising on strength in Amazon and Nvidia while the S&amp;P 500 and Dow turned lower intraday. Cryptocurrencies plunged sharply, with Bitcoin down over 4% below $106,000 and Ethereum losing more than 8%. Spot gold rebounded back above $4,000 after an intraday dip, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3039,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[8],"tags":[],"class_list":["post-3038","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-english-news","entry","has-media"],"_links":{"self":[{"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/posts\/3038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/comments?post=3038"}],"version-history":[{"count":2,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/posts\/3038\/revisions"}],"predecessor-version":[{"id":3041,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/posts\/3038\/revisions\/3041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/media\/3039"}],"wp:attachment":[{"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/media?parent=3038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/categories?post=3038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.amillex.com\/de\/wp-json\/wp\/v2\/tags?post=3038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}